{"id":3119,"date":"2025-06-06T17:10:47","date_gmt":"2025-06-06T17:10:47","guid":{"rendered":"https:\/\/dmare.pt\/?post_type=event&#038;p=3119"},"modified":"2026-04-29T16:50:37","modified_gmt":"2026-04-29T16:50:37","slug":"menu-sunset-make-your-sunset","status":"publish","type":"event","link":"https:\/\/dmare.pt\/es\/evento\/menu-sunset-make-your-sunset\/","title":{"rendered":"Menu Sunset \u201cMake Your Sunset\u201d"},"content":{"rendered":"<h2>Totalmente personalizado, a tu gusto.<\/h2>\n<p>\u00bfBuscas algo diferente? \u00a1Cont\u00e1ctanos! Elaboraremos una propuesta a tu medida con:<\/p>\n<table>\n<thead>\n<tr>\n<th style=\"text-align: left;\">Inclui:<\/th>\n<th><\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr class=\"odd\">\n<td><a href=\"#\">Snacks de tu elecci\u00f3n<\/a><\/td>\n<td><a href=\"#\">Bebidas personalizadas (con opci\u00f3n de barra libre)<\/a><\/td>\n<\/tr>\n<tr class=\"even\">\n<td><a href=\"#\">Decoraci\u00f3n especial o entretenimiento (sujeto a presupuesto)<\/a><\/td>\n<td><a href=\"#\">Opci\u00f3n de ampliar horario o espacio exclusivo<\/a><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>M\u00ednimo: 10 personas \u2022 Duraci\u00f3n: 4 horas \u2022 Servicio en terraza o interior.<br \/>\nBajo presupuesto, con apoyo directo de nuestro equipo.<br \/>\nIdeal para empresas, cumplea\u00f1os o eventos \u00fanicos.<br \/>\nPara mais informa\u00e7\u00f5es ou reservas: M. 917 774 486 \u2022 E. <a href=\"mailto:reservas@dmare.pt;\">reservas@dmare.pt<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Totalmente personalizado, a tu gusto. \u00bfBuscas algo diferente? \u00a1Cont\u00e1ctanos! Creamos una propuesta a tu medida.<\/p>","protected":false},"author":1,"featured_media":2863,"parent":0,"comment_status":"closed","ping_status":"closed","template":"","category-event":[97],"class_list":["post-3119","event","type-event","status-publish","has-post-thumbnail","hentry","category-event-sunset"],"_links":{"self":[{"href":"https:\/\/dmare.pt\/es\/wp-json\/wp\/v2\/event\/3119","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dmare.pt\/es\/wp-json\/wp\/v2\/event"}],"about":[{"href":"https:\/\/dmare.pt\/es\/wp-json\/wp\/v2\/types\/event"}],"author":[{"embeddable":true,"href":"https:\/\/dmare.pt\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dmare.pt\/es\/wp-json\/wp\/v2\/comments?post=3119"}],"version-history":[{"count":4,"href":"https:\/\/dmare.pt\/es\/wp-json\/wp\/v2\/event\/3119\/revisions"}],"predecessor-version":[{"id":3137,"href":"https:\/\/dmare.pt\/es\/wp-json\/wp\/v2\/event\/3119\/revisions\/3137"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dmare.pt\/es\/wp-json\/wp\/v2\/media\/2863"}],"wp:attachment":[{"href":"https:\/\/dmare.pt\/es\/wp-json\/wp\/v2\/media?parent=3119"}],"wp:term":[{"taxonomy":"category-event","embeddable":true,"href":"https:\/\/dmare.pt\/es\/wp-json\/wp\/v2\/category-event?post=3119"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}